{"id":2807,"date":"2023-05-03T09:55:04","date_gmt":"2023-05-03T08:55:04","guid":{"rendered":"https:\/\/wp.dev.blancabikes.pirstack.com\/news\/lancien-champion-du-monde-de-cyclisme-colin-sturgess-rejoint-blanca-bikes\/"},"modified":"2024-03-08T11:25:55","modified_gmt":"2024-03-08T11:25:55","slug":"lancien-champion-du-monde-de-cyclisme-colin-sturgess-rejoint-blanca-bikes","status":"publish","type":"post","link":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/news\/lancien-champion-du-monde-de-cyclisme-colin-sturgess-rejoint-blanca-bikes\/","title":{"rendered":"L&rsquo;ancien champion du monde de cyclisme Colin Sturgess rejoint Blanca Bikes"},"content":{"rendered":"<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1239790 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1239790\" data-element_type=\"section\" data-settings=\"{\">\n<div class=\"elementor-container elementor-column-gap-no\">\n<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-41e16e8\" data-id=\"41e16e8\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-998c21f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"998c21f\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6ee24fe\" data-id=\"6ee24fe\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-ef32755 elementor-widget elementor-widget-text-editor\" data-id=\"ef32755\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p><strong>Blanca Bikes a le plaisir d&rsquo;annoncer l&rsquo;arriv\u00e9e d&rsquo;un nouveau membre dans son \u00e9quipe : Colin Sturgess, ancien champion du monde et champion britannique de cyclisme, rejoindra l&rsquo;\u00e9quipe de Blanca Bikes en tant que guide cycliste principal et partagera avec les clients de Blanca Bikes ses connaissances du cyclisme, ses comp\u00e9tences et son amour de la Costa Blanca.<\/strong><\/p>\n<p><strong>Colin apporte une grande exp\u00e9rience (et de nombreuses histoires) \u00e0 l&rsquo;\u00e9quipe et, gr\u00e2ce \u00e0 sa connaissance approfondie de la r\u00e9gion, il organisera des<a href=\"https:\/\/blancabikes.com\/fr\/circuits-cyclistes-guides\/\">randonn\u00e9es guid\u00e9es<\/a> sur&nbsp;&nbsp; dans la magnifique campagne qui se trouve \u00e0 notre porte.<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6731002 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6731002\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-028dacd\" data-id=\"028dacd\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-9cc525c elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"9cc525c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>Colin est un ancien cycliste professionnel britannique qui a commenc\u00e9 sa carri\u00e8re en tant que cycliste sur piste, remportant plusieurs titres nationaux en poursuite individuelle et en course aux points dans les ann\u00e9es 1980. En 1990, Colin est pass\u00e9 au cyclisme sur route et s&rsquo;est rapidement impos\u00e9 comme l&rsquo;un des meilleurs coureurs britanniques de sa g\u00e9n\u00e9ration. Il a remport\u00e9 le championnat national britannique de course sur route en 1990 et 1991, et a \u00e9galement particip\u00e9 au Tour de France en 1991 et 1993. Colin \u00e9tait connu pour ses capacit\u00e9s de grimpeur et r\u00e9ussissait particuli\u00e8rement bien dans les courses vallonn\u00e9es. Il a remport\u00e9 le classement \u00ab\u00a0King of the Mountains\u00a0\u00bb du Tour de Grande-Bretagne en 1992 et 1994, ainsi que la prestigieuse Milk Race en 1992.<\/p>\n<p>En plus de ses succ\u00e8s sur la route, Colin a continu\u00e9 \u00e0 participer \u00e0 des \u00e9preuves de cyclisme sur piste tout au long de sa carri\u00e8re. Il a remport\u00e9 la poursuite individuelle lors des championnats du monde de cyclisme sur piste de l&rsquo;UCI en 1993, devenant ainsi le premier coureur britannique \u00e0 remporter un titre mondial dans cette \u00e9preuve depuis plus de 70 ans.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d1a72cc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d1a72cc\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5290ea3\" data-id=\"5290ea3\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-a3c1429 elementor-widget elementor-widget-text-editor\" data-id=\"a3c1429\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>Nous nous sentons tous tr\u00e8s chanceux ici \u00e0&nbsp;<a href=\"https:\/\/blancabikes.com\/fr\/\">Blanca Bikes<\/a>&nbsp;que Colin a choisi de se joindre \u00e0 nous et de partager ses comp\u00e9tences et son expertise avec nos vacances \u00e0 v\u00e9lo,&nbsp;la <a href=\"https:\/\/blancabikes.com\/fr\/location-de-velos-2\/\">location de v\u00e9los<\/a>&nbsp;et les clients des visites guid\u00e9es. Sous la conduite de Colin, nous pouvons adapter votre exp\u00e9rience de randonn\u00e9e guid\u00e9e d&rsquo;une heure \u00e0 six ou sept heures. Colin peut vous guider sur certaines des ascensions et voies les plus embl\u00e9matiques, telles que&nbsp;<a href=\"https:\/\/blancabikes.com\/best-costa-blanca-cycling-routes\/\">Col de Rates<\/a>, Tudons, Vall de Gallinara, Val de Ebo, Tollos, Tarbena, Guadalest ou les routes plates et rapides de Pego et au-del\u00e0. Un certain niveau de forme physique est requis, de m\u00eame qu&rsquo;une bonne ma\u00eetrise du v\u00e9lo.<\/p>\n<p>Colin s&rsquo;est retir\u00e9 du cyclisme professionnel en 2000 et est devenu depuis entra\u00eeneur et commentateur cycliste. Il a entra\u00een\u00e9 plusieurs cyclistes de haut niveau, dont le m\u00e9daill\u00e9 d&rsquo;or olympique Bradley Wiggins et l&rsquo;ancien champion du monde Mark Cavendish. Bien qu&rsquo;il se soit retir\u00e9 du cyclisme de comp\u00e9tition il y a plus de 20 ans, Colin reste une figure respect\u00e9e dans le monde du cyclisme. Ses exploits en tant que coureur et entra\u00eeneur lui ont valu une place dans l&rsquo;histoire du cyclisme britannique, et il continue d&rsquo;inspirer et d&rsquo;encadrer la prochaine g\u00e9n\u00e9ration de coureurs, y compris ceux qui nous rendent visite ici, chez Blanca Bikes.<\/p>\n<p>Veuillez contacter Blanca Bikes pour plus d&rsquo;informations sur la r\u00e9servation d&rsquo;une visite guid\u00e9e \u00e0 v\u00e9lo avec Colin ou d&rsquo;autres membres de notre \u00e9quipe de guides exp\u00e9riment\u00e9s.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Blanca Bikes a le plaisir d&rsquo;annoncer l&rsquo;arriv\u00e9e d&rsquo;un nouveau membre dans son \u00e9quipe : Colin Sturgess, ancien champion du monde et champion britannique de cyclisme, rejoindra l&rsquo;\u00e9quipe de Blanca Bikes en tant que guide cycliste principal et partagera avec les clients de Blanca Bikes ses connaissances du cyclisme, ses comp\u00e9tences et son amour de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2115,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-2807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;ancien champion du monde de cyclisme Colin Sturgess<\/title>\n<meta name=\"description\" content=\"L&#039;ancien champion du monde de cyclisme Colin Sturgess rejoint Blanca Bikes. Cliquez ici.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;ancien champion du monde de cyclisme Colin Sturgess\" \/>\n<meta property=\"og:description\" content=\"L&#039;ancien champion du monde de cyclisme Colin Sturgess rejoint Blanca Bikes. Cliquez ici.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/news\/lancien-champion-du-monde-de-cyclisme-colin-sturgess-rejoint-blanca-bikes\/\" \/>\n<meta property=\"og:site_name\" content=\"Blanca Bikes\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-03T08:55:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-08T11:25:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wp.dev.blanca.pirstack.com\/wp-content\/uploads\/2023\/11\/Colin-Sturgess-Champoin-Cyclist-Blanca-Bikes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"piranha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"piranha\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/news\/lancien-champion-du-monde-de-cyclisme-colin-sturgess-rejoint-blanca-bikes\/\",\"url\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/news\/lancien-champion-du-monde-de-cyclisme-colin-sturgess-rejoint-blanca-bikes\/\",\"name\":\"L'ancien champion du monde de cyclisme Colin Sturgess\",\"isPartOf\":{\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/#website\"},\"datePublished\":\"2023-05-03T08:55:04+00:00\",\"dateModified\":\"2024-03-08T11:25:55+00:00\",\"author\":{\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/#\/schema\/person\/1de2859f930e58ab3d39a12c1da68893\"},\"description\":\"L'ancien champion du monde de cyclisme Colin Sturgess rejoint Blanca Bikes. Cliquez ici.\",\"breadcrumb\":{\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/news\/lancien-champion-du-monde-de-cyclisme-colin-sturgess-rejoint-blanca-bikes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/news\/lancien-champion-du-monde-de-cyclisme-colin-sturgess-rejoint-blanca-bikes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/news\/lancien-champion-du-monde-de-cyclisme-colin-sturgess-rejoint-blanca-bikes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;ancien champion du monde de cyclisme Colin Sturgess rejoint Blanca Bikes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/#website\",\"url\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/\",\"name\":\"Blanca Bikes\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/#\/schema\/person\/1de2859f930e58ab3d39a12c1da68893\",\"name\":\"piranha\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4c19455676cdb6d360be20bffa35fa495847f2ffce91fffbd483a3f13a872014?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4c19455676cdb6d360be20bffa35fa495847f2ffce91fffbd483a3f13a872014?s=96&d=mm&r=g\",\"caption\":\"piranha\"},\"sameAs\":[\"https:\/\/wp.dev.blancabikes.pirstack.com\"],\"url\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/news\/author\/piranha\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'ancien champion du monde de cyclisme Colin Sturgess","description":"L'ancien champion du monde de cyclisme Colin Sturgess rejoint Blanca Bikes. Cliquez ici.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"L'ancien champion du monde de cyclisme Colin Sturgess","og_description":"L'ancien champion du monde de cyclisme Colin Sturgess rejoint Blanca Bikes. Cliquez ici.","og_url":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/news\/lancien-champion-du-monde-de-cyclisme-colin-sturgess-rejoint-blanca-bikes\/","og_site_name":"Blanca Bikes","article_published_time":"2023-05-03T08:55:04+00:00","article_modified_time":"2024-03-08T11:25:55+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/wp.dev.blanca.pirstack.com\/wp-content\/uploads\/2023\/11\/Colin-Sturgess-Champoin-Cyclist-Blanca-Bikes.jpg","type":"image\/jpeg"}],"author":"piranha","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"piranha","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/news\/lancien-champion-du-monde-de-cyclisme-colin-sturgess-rejoint-blanca-bikes\/","url":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/news\/lancien-champion-du-monde-de-cyclisme-colin-sturgess-rejoint-blanca-bikes\/","name":"L'ancien champion du monde de cyclisme Colin Sturgess","isPartOf":{"@id":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/#website"},"datePublished":"2023-05-03T08:55:04+00:00","dateModified":"2024-03-08T11:25:55+00:00","author":{"@id":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/#\/schema\/person\/1de2859f930e58ab3d39a12c1da68893"},"description":"L'ancien champion du monde de cyclisme Colin Sturgess rejoint Blanca Bikes. Cliquez ici.","breadcrumb":{"@id":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/news\/lancien-champion-du-monde-de-cyclisme-colin-sturgess-rejoint-blanca-bikes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wp.dev.blanca.pirstack.com\/fr\/news\/lancien-champion-du-monde-de-cyclisme-colin-sturgess-rejoint-blanca-bikes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/news\/lancien-champion-du-monde-de-cyclisme-colin-sturgess-rejoint-blanca-bikes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;ancien champion du monde de cyclisme Colin Sturgess rejoint Blanca Bikes"}]},{"@type":"WebSite","@id":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/#website","url":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/","name":"Blanca Bikes","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/#\/schema\/person\/1de2859f930e58ab3d39a12c1da68893","name":"piranha","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4c19455676cdb6d360be20bffa35fa495847f2ffce91fffbd483a3f13a872014?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c19455676cdb6d360be20bffa35fa495847f2ffce91fffbd483a3f13a872014?s=96&d=mm&r=g","caption":"piranha"},"sameAs":["https:\/\/wp.dev.blancabikes.pirstack.com"],"url":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/news\/author\/piranha\/"}]}},"_links":{"self":[{"href":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/wp-json\/wp\/v2\/posts\/2807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/wp-json\/wp\/v2\/comments?post=2807"}],"version-history":[{"count":2,"href":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/wp-json\/wp\/v2\/posts\/2807\/revisions"}],"predecessor-version":[{"id":3814,"href":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/wp-json\/wp\/v2\/posts\/2807\/revisions\/3814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/wp-json\/wp\/v2\/media\/2115"}],"wp:attachment":[{"href":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/wp-json\/wp\/v2\/media?parent=2807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/wp-json\/wp\/v2\/categories?post=2807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/wp-json\/wp\/v2\/tags?post=2807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}