{"id":2628,"date":"2023-11-15T15:19:08","date_gmt":"2023-11-15T15:19:08","guid":{"rendered":"https:\/\/wp.dev.blancabikes.pirstack.com\/camps-dentrainement-de-cyclisme-de-performance-costa-blanca\/"},"modified":"2025-10-22T11:55:06","modified_gmt":"2025-10-22T10:55:06","slug":"camps-dentrainement-de-cyclisme-de-performance-costa-blanca","status":"publish","type":"page","link":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/camps-dentrainement-de-cyclisme-de-performance-costa-blanca\/","title":{"rendered":"Camps d&rsquo;entra\u00eenement de cyclisme de performance &#8211; Costa Blanca"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-2628","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Camps d&#039;entra\u00eenement de cyclisme de performance - Costa Blanca - Blanca Bikes<\/title>\n<meta name=\"description\" content=\"Faites passer votre cyclisme au niveau sup\u00e9rieur et rejoignez-nous sur la Costa Blanca pour l&#039;un de nos camps d&#039;entra\u00eenement de cyclisme de haute performance.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Camps d&#039;entra\u00eenement de cyclisme de performance - Costa Blanca - Blanca Bikes\" \/>\n<meta property=\"og:description\" content=\"Faites passer votre cyclisme au niveau sup\u00e9rieur et rejoignez-nous sur la Costa Blanca pour l&#039;un de nos camps d&#039;entra\u00eenement de cyclisme de haute performance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/camps-dentrainement-de-cyclisme-de-performance-costa-blanca\/\" \/>\n<meta property=\"og:site_name\" content=\"Blanca Bikes\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-22T10:55:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/camps-dentrainement-de-cyclisme-de-performance-costa-blanca\/\",\"url\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/camps-dentrainement-de-cyclisme-de-performance-costa-blanca\/\",\"name\":\"Camps d'entra\u00eenement de cyclisme de performance - Costa Blanca - Blanca Bikes\",\"isPartOf\":{\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/#website\"},\"datePublished\":\"2023-11-15T15:19:08+00:00\",\"dateModified\":\"2025-10-22T10:55:06+00:00\",\"description\":\"Faites passer votre cyclisme au niveau sup\u00e9rieur et rejoignez-nous sur la Costa Blanca pour l'un de nos camps d'entra\u00eenement de cyclisme de haute performance.\",\"breadcrumb\":{\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/camps-dentrainement-de-cyclisme-de-performance-costa-blanca\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/camps-dentrainement-de-cyclisme-de-performance-costa-blanca\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/camps-dentrainement-de-cyclisme-de-performance-costa-blanca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Camps d&rsquo;entra\u00eenement de cyclisme de performance &#8211; Costa Blanca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/#website\",\"url\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/\",\"name\":\"Blanca Bikes\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wp.dev.blanca.pirstack.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Camps d'entra\u00eenement de cyclisme de performance - Costa Blanca - Blanca Bikes","description":"Faites passer votre cyclisme au niveau sup\u00e9rieur et rejoignez-nous sur la Costa Blanca pour l'un de nos camps d'entra\u00eenement de cyclisme de haute performance.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Camps d'entra\u00eenement de cyclisme de performance - Costa Blanca - Blanca Bikes","og_description":"Faites passer votre cyclisme au niveau sup\u00e9rieur et rejoignez-nous sur la Costa Blanca pour l'un de nos camps d'entra\u00eenement de cyclisme de haute performance.","og_url":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/camps-dentrainement-de-cyclisme-de-performance-costa-blanca\/","og_site_name":"Blanca Bikes","article_modified_time":"2025-10-22T10:55:06+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/camps-dentrainement-de-cyclisme-de-performance-costa-blanca\/","url":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/camps-dentrainement-de-cyclisme-de-performance-costa-blanca\/","name":"Camps d'entra\u00eenement de cyclisme de performance - Costa Blanca - Blanca Bikes","isPartOf":{"@id":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/#website"},"datePublished":"2023-11-15T15:19:08+00:00","dateModified":"2025-10-22T10:55:06+00:00","description":"Faites passer votre cyclisme au niveau sup\u00e9rieur et rejoignez-nous sur la Costa Blanca pour l'un de nos camps d'entra\u00eenement de cyclisme de haute performance.","breadcrumb":{"@id":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/camps-dentrainement-de-cyclisme-de-performance-costa-blanca\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wp.dev.blanca.pirstack.com\/fr\/camps-dentrainement-de-cyclisme-de-performance-costa-blanca\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/camps-dentrainement-de-cyclisme-de-performance-costa-blanca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Camps d&rsquo;entra\u00eenement de cyclisme de performance &#8211; Costa Blanca"}]},{"@type":"WebSite","@id":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/#website","url":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/","name":"Blanca Bikes","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/wp-json\/wp\/v2\/pages\/2628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/wp-json\/wp\/v2\/comments?post=2628"}],"version-history":[{"count":1,"href":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/wp-json\/wp\/v2\/pages\/2628\/revisions"}],"predecessor-version":[{"id":2890,"href":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/wp-json\/wp\/v2\/pages\/2628\/revisions\/2890"}],"wp:attachment":[{"href":"https:\/\/wp.dev.blanca.pirstack.com\/fr\/wp-json\/wp\/v2\/media?parent=2628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}