{"id":3349,"date":"2022-11-10T09:50:20","date_gmt":"2022-11-10T09:50:20","guid":{"rendered":"https:\/\/blancabikes.com\/news\/nuevo-ya-esta-disponible-el-kit-de-ciclismo-de-blanca-bikes\/"},"modified":"2024-03-08T11:25:28","modified_gmt":"2024-03-08T11:25:28","slug":"nuevo-ya-esta-disponible-el-kit-de-ciclismo-de-blanca-bikes","status":"publish","type":"post","link":"https:\/\/wp.dev.blanca.pirstack.com\/es\/news\/nuevo-ya-esta-disponible-el-kit-de-ciclismo-de-blanca-bikes\/","title":{"rendered":"NUEVO- Ya est\u00e1 disponible el kit de ciclismo de Blanca Bikes"},"content":{"rendered":"<p>De nada sirve tener una bicicleta de carretera de aspecto deslumbrante si pedaleas con \u00ablos colores del a\u00f1o pasado\u00bb. Nuestro esperado nuevo kit de ciclismo ya est\u00e1 disponible en Blanca Bikes. Hemos renovado el dise\u00f1o de nuestro culotte y maillot a tiempo para la temporada alta de ciclismo Costa Blanca 2022\/23 y ya est\u00e1n de camino. Los maillots tienen un precio de s\u00f3lo 75 euros, y los culottes, de s\u00f3lo 85 euros,<\/p>\n<p>Para pedir su nuevo equipo de ciclismo, env\u00edenos un correo electr\u00f3nico a&nbsp;Info@BlancaBikes.com&nbsp;o rellene nuestro&nbsp;<a href=\"https:\/\/blancabikes.com\/contact\/\">formulario de consulta en l\u00ednea&nbsp; &nbsp;<\/a><\/p>\n<p>Esperamos verles a todos en la carretera con su mejor aspecto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-806\" src=\"https:\/\/blancabikes.com\/wp-content\/uploads\/2023\/11\/jersey.png\" alt=\"\" width=\"1469\" height=\"907\" srcset=\"https:\/\/wp.dev.blanca.pirstack.com\/wp-content\/uploads\/2023\/11\/jersey.png 1469w, https:\/\/wp.dev.blanca.pirstack.com\/wp-content\/uploads\/2023\/11\/jersey-300x185.png 300w, https:\/\/wp.dev.blanca.pirstack.com\/wp-content\/uploads\/2023\/11\/jersey-1024x632.png 1024w, https:\/\/wp.dev.blanca.pirstack.com\/wp-content\/uploads\/2023\/11\/jersey-768x474.png 768w\" sizes=\"auto, (max-width: 1469px) 100vw, 1469px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De nada sirve tener una bicicleta de carretera de aspecto deslumbrante si pedaleas con \u00ablos colores del a\u00f1o pasado\u00bb. Nuestro esperado nuevo kit de ciclismo ya est\u00e1 disponible en Blanca Bikes. Hemos renovado el dise\u00f1o de nuestro culotte y maillot a tiempo para la temporada alta de ciclismo Costa Blanca 2022\/23 y ya est\u00e1n de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3350,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-3349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>NUEVO- Ya est\u00e1 disponible el kit de ciclismo de Blanca Bikes<\/title>\n<meta name=\"description\" content=\"Nuestro esperado nuevo kit de ciclismo ya est\u00e1 disponible en Blanca Bikes. Haga clic en el enlace para verlo.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NUEVO- Ya est\u00e1 disponible el kit de ciclismo de Blanca Bikes\" \/>\n<meta property=\"og:description\" content=\"Nuestro esperado nuevo kit de ciclismo ya est\u00e1 disponible en Blanca Bikes. Haga clic en el enlace para verlo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wp.dev.blanca.pirstack.com\/es\/news\/nuevo-ya-esta-disponible-el-kit-de-ciclismo-de-blanca-bikes\/\" \/>\n<meta property=\"og:site_name\" content=\"Blanca Bikes\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-10T09:50:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-08T11:25:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wp.dev.blanca.pirstack.com\/wp-content\/uploads\/2023\/11\/Blanca-Bikes-Cycling-Jersey-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"612\" \/>\n\t<meta property=\"og:image:height\" content=\"772\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"piranha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"piranha\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/es\/news\/nuevo-ya-esta-disponible-el-kit-de-ciclismo-de-blanca-bikes\/\",\"url\":\"https:\/\/wp.dev.blanca.pirstack.com\/es\/news\/nuevo-ya-esta-disponible-el-kit-de-ciclismo-de-blanca-bikes\/\",\"name\":\"NUEVO- Ya est\u00e1 disponible el kit de ciclismo de Blanca Bikes\",\"isPartOf\":{\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/es\/#website\"},\"datePublished\":\"2022-11-10T09:50:20+00:00\",\"dateModified\":\"2024-03-08T11:25:28+00:00\",\"author\":{\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/es\/#\/schema\/person\/1de2859f930e58ab3d39a12c1da68893\"},\"description\":\"Nuestro esperado nuevo kit de ciclismo ya est\u00e1 disponible en Blanca Bikes. Haga clic en el enlace para verlo.\",\"breadcrumb\":{\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/es\/news\/nuevo-ya-esta-disponible-el-kit-de-ciclismo-de-blanca-bikes\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wp.dev.blanca.pirstack.com\/es\/news\/nuevo-ya-esta-disponible-el-kit-de-ciclismo-de-blanca-bikes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/es\/news\/nuevo-ya-esta-disponible-el-kit-de-ciclismo-de-blanca-bikes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/wp.dev.blanca.pirstack.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NUEVO- Ya est\u00e1 disponible el kit de ciclismo de Blanca Bikes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/es\/#website\",\"url\":\"https:\/\/wp.dev.blanca.pirstack.com\/es\/\",\"name\":\"Blanca Bikes\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wp.dev.blanca.pirstack.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/es\/#\/schema\/person\/1de2859f930e58ab3d39a12c1da68893\",\"name\":\"piranha\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4c19455676cdb6d360be20bffa35fa495847f2ffce91fffbd483a3f13a872014?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4c19455676cdb6d360be20bffa35fa495847f2ffce91fffbd483a3f13a872014?s=96&d=mm&r=g\",\"caption\":\"piranha\"},\"sameAs\":[\"https:\/\/wp.dev.blancabikes.pirstack.com\"],\"url\":\"https:\/\/wp.dev.blanca.pirstack.com\/es\/news\/author\/piranha\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NUEVO- Ya est\u00e1 disponible el kit de ciclismo de Blanca Bikes","description":"Nuestro esperado nuevo kit de ciclismo ya est\u00e1 disponible en Blanca Bikes. Haga clic en el enlace para verlo.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"NUEVO- Ya est\u00e1 disponible el kit de ciclismo de Blanca Bikes","og_description":"Nuestro esperado nuevo kit de ciclismo ya est\u00e1 disponible en Blanca Bikes. Haga clic en el enlace para verlo.","og_url":"https:\/\/wp.dev.blanca.pirstack.com\/es\/news\/nuevo-ya-esta-disponible-el-kit-de-ciclismo-de-blanca-bikes\/","og_site_name":"Blanca Bikes","article_published_time":"2022-11-10T09:50:20+00:00","article_modified_time":"2024-03-08T11:25:28+00:00","og_image":[{"width":612,"height":772,"url":"https:\/\/wp.dev.blanca.pirstack.com\/wp-content\/uploads\/2023\/11\/Blanca-Bikes-Cycling-Jersey-1.jpg","type":"image\/jpeg"}],"author":"piranha","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"piranha","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wp.dev.blanca.pirstack.com\/es\/news\/nuevo-ya-esta-disponible-el-kit-de-ciclismo-de-blanca-bikes\/","url":"https:\/\/wp.dev.blanca.pirstack.com\/es\/news\/nuevo-ya-esta-disponible-el-kit-de-ciclismo-de-blanca-bikes\/","name":"NUEVO- Ya est\u00e1 disponible el kit de ciclismo de Blanca Bikes","isPartOf":{"@id":"https:\/\/wp.dev.blanca.pirstack.com\/es\/#website"},"datePublished":"2022-11-10T09:50:20+00:00","dateModified":"2024-03-08T11:25:28+00:00","author":{"@id":"https:\/\/wp.dev.blanca.pirstack.com\/es\/#\/schema\/person\/1de2859f930e58ab3d39a12c1da68893"},"description":"Nuestro esperado nuevo kit de ciclismo ya est\u00e1 disponible en Blanca Bikes. Haga clic en el enlace para verlo.","breadcrumb":{"@id":"https:\/\/wp.dev.blanca.pirstack.com\/es\/news\/nuevo-ya-esta-disponible-el-kit-de-ciclismo-de-blanca-bikes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wp.dev.blanca.pirstack.com\/es\/news\/nuevo-ya-esta-disponible-el-kit-de-ciclismo-de-blanca-bikes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wp.dev.blanca.pirstack.com\/es\/news\/nuevo-ya-esta-disponible-el-kit-de-ciclismo-de-blanca-bikes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wp.dev.blanca.pirstack.com\/es\/"},{"@type":"ListItem","position":2,"name":"NUEVO- Ya est\u00e1 disponible el kit de ciclismo de Blanca Bikes"}]},{"@type":"WebSite","@id":"https:\/\/wp.dev.blanca.pirstack.com\/es\/#website","url":"https:\/\/wp.dev.blanca.pirstack.com\/es\/","name":"Blanca Bikes","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wp.dev.blanca.pirstack.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/wp.dev.blanca.pirstack.com\/es\/#\/schema\/person\/1de2859f930e58ab3d39a12c1da68893","name":"piranha","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/wp.dev.blanca.pirstack.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4c19455676cdb6d360be20bffa35fa495847f2ffce91fffbd483a3f13a872014?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c19455676cdb6d360be20bffa35fa495847f2ffce91fffbd483a3f13a872014?s=96&d=mm&r=g","caption":"piranha"},"sameAs":["https:\/\/wp.dev.blancabikes.pirstack.com"],"url":"https:\/\/wp.dev.blanca.pirstack.com\/es\/news\/author\/piranha\/"}]}},"_links":{"self":[{"href":"https:\/\/wp.dev.blanca.pirstack.com\/es\/wp-json\/wp\/v2\/posts\/3349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.dev.blanca.pirstack.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.dev.blanca.pirstack.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.dev.blanca.pirstack.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.dev.blanca.pirstack.com\/es\/wp-json\/wp\/v2\/comments?post=3349"}],"version-history":[{"count":1,"href":"https:\/\/wp.dev.blanca.pirstack.com\/es\/wp-json\/wp\/v2\/posts\/3349\/revisions"}],"predecessor-version":[{"id":3813,"href":"https:\/\/wp.dev.blanca.pirstack.com\/es\/wp-json\/wp\/v2\/posts\/3349\/revisions\/3813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.dev.blanca.pirstack.com\/es\/wp-json\/wp\/v2\/media\/3350"}],"wp:attachment":[{"href":"https:\/\/wp.dev.blanca.pirstack.com\/es\/wp-json\/wp\/v2\/media?parent=3349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.dev.blanca.pirstack.com\/es\/wp-json\/wp\/v2\/categories?post=3349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.dev.blanca.pirstack.com\/es\/wp-json\/wp\/v2\/tags?post=3349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}