{"id":2810,"date":"2023-05-18T09:58:34","date_gmt":"2023-05-18T08:58:34","guid":{"rendered":"https:\/\/wp.dev.blancabikes.pirstack.com\/news\/2023-uci-radweltmeisterschaften-3-bis-13-august-glasgow\/"},"modified":"2024-01-16T12:50:21","modified_gmt":"2024-01-16T12:50:21","slug":"2023-uci-radweltmeisterschaften-3-bis-13-august-glasgow","status":"publish","type":"post","link":"https:\/\/wp.dev.blanca.pirstack.com\/de\/news\/2023-uci-radweltmeisterschaften-3-bis-13-august-glasgow\/","title":{"rendered":"2023 UCI-Radweltmeisterschaften, 3. bis 13. August, Glasgow."},"content":{"rendered":"<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c314bf5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c314bf5\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-15fd244\" data-id=\"15fd244\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-e2ff035 elementor-widget elementor-widget-text-editor\" data-id=\"e2ff035\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>Die mit Spannung erwarteten UCI-Radsport-Weltmeisterschaften 2023 finden vom 3. bis 13. August 2023 statt und werden die Stadt Glasgow in ihren Bann ziehen und die wundersch\u00f6ne Landschaft Schottlands durchqueren. W\u00e4hrend die weltweite Radsportgemeinde diesem prestigetr\u00e4chtigen Ereignis entgegenfiebert, laufen die Vorbereitungen f\u00fcr ein unvergessliches Erlebnis f\u00fcr Sportler und Zuschauer gleicherma\u00dfen.<\/p>\n<p>Glasgow, eine Stadt, die f\u00fcr ihre pulsierende Energie und ihre Liebe zum Sport bekannt ist, wurde als Hauptausrichter f\u00fcr die Meisterschaften ausgew\u00e4hlt. Die moderne Infrastruktur, die Sporteinrichtungen von Weltklasse und die leidenschaftliche Radsportkultur machen die Stadt zu einem idealen Ort, um die Spitze des internationalen Radsports zu pr\u00e4sentieren. Die Meisterschaften beschr\u00e4nken sich jedoch nicht auf die Stadtgrenzen, denn die verschiedenen Rennen und Veranstaltungen finden in verschiedenen Regionen Schottlands statt und bieten eine einzigartige Gelegenheit, die vielf\u00e4ltigen und malerischen Landschaften des Landes zu erkunden.<\/p>\n<p>W\u00e4hrend der Meisterschaften wird eine breite Palette von Radsportdisziplinen geboten, darunter Stra\u00dfenrennen, Zeitfahren, Bahnradfahren, Mountainbiking und BMX. Die besten Radsportler der Welt treffen sich, um um die prestigetr\u00e4chtigen Regenbogentrikots zu k\u00e4mpfen, die ihren Status als die Besten in ihren jeweiligen Disziplinen symbolisieren und ihnen einen Platz in der Radsportgeschichte sichern.<\/p>\n<p>Die Stra\u00dfenrennen f\u00fchren die Teilnehmer auf eine aufregende Reise durch die atemberaubende Landschaft Schottlands. Die Radfahrer befahren anspruchsvolle Strecken, schl\u00e4ngeln sich durch sanfte H\u00fcgel, nehmen kurvenreiche Stra\u00dfen in Angriff und durchqueren atemberaubende Landschaften. Die Zuschauer entlang der Strecken werden mit dem Spektakel des Pelotons konfrontiert, das an ikonischen Wahrzeichen vorbeif\u00e4hrt und eine elektrisierende Atmosph\u00e4re schafft, die die Leidenschaft f\u00fcr den Radsport verk\u00f6rpert.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c27c1df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c27c1df\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-af563f7\" data-id=\"af563f7\" data-element_type=\"column\">\n<div class=\"elementor-widget-wrap elementor-element-populated\">\n<div class=\"elementor-element elementor-element-d072692 elementor-widget elementor-widget-text-editor\" data-id=\"d072692\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>Bei den Zeitfahrwettbewerben k\u00e4mpfen die Athleten gegen die Uhr und gegen sich selbst, indem sie an ihre Grenzen gehen, um die schnellsten Zeiten zu erzielen. Von anspruchsvollen K\u00fcstenstrecken bis hin zu zerm\u00fcrbenden Anstiegen werden die Zeitfahren die Kraft, die Ausdauer und das strategische Geschick der Radfahrer auf die Probe stellen. Jeder Fahrer wird bestrebt sein, eine au\u00dfergew\u00f6hnliche Leistung zu erbringen und sich den Sieg in diesem ultimativen Test des individuellen K\u00f6nnens zu sichern.<\/p>\n<p>Das Velodrom in Glasgow wird der Schauplatz f\u00fcr die Bahnradrennen sein. In dieser hochmodernen Anlage k\u00f6nnen die Athleten ihre Schnelligkeit, Beweglichkeit und Pr\u00e4zision unter Beweis stellen, wenn sie die steilen Kurven und aufregenden Geraden bew\u00e4ltigen. Die Zuschauer k\u00f6nnen sich auf packende Rennen, Geschicklichkeit und Taktik freuen, wenn die Radsportler auf der ehrw\u00fcrdigen Strecke des Velodroms um den Ruhm k\u00e4mpfen.<\/p>\n<p>Die Meisterschaften werden auch die spannenden Offroad-Disziplinen umfassen. Die Mountainbike-Veranstaltungen f\u00fchren die Teilnehmer durch die rauen und faszinierenden Landschaften Schottlands und bieten anspruchsvolle Abfahrten, technische Abschnitte und adrenalingeladene Rennen. BMX-Fahrer hingegen werden das Publikum auf Glasgows eigens angelegten Strecken in ihren Bann ziehen und der Schwerkraft mit waghalsigen Man\u00f6vern und aufregenden Rennen trotzen.<\/p>\n<p>\u00dcber die Wettk\u00e4mpfe hinaus werden die UCI-Radweltmeisterschaften 2023 einen Geist der Einheit und Kameradschaft f\u00f6rdern. Die Organisatoren der Veranstaltung planen verschiedene Programme zur Einbindung der Bev\u00f6lkerung, um Menschen jeden Alters und jeder Herkunft zu ermutigen, an radsportbezogenen Aktivit\u00e4ten teilzunehmen und sich den integrativen und gesunden Lebensstil des Sports zu Eigen zu machen. Diese Initiativen werden daf\u00fcr sorgen, dass die Meisterschaften ein bleibendes Verm\u00e4chtnis hinterlassen, das k\u00fcnftige Generationen von Radfahrern inspiriert und die Vorteile des Radfahrens in ganz Schottland f\u00f6rdert.<\/p>\n<p>Der Countdown f\u00fcr die UCI-Radweltmeisterschaften 2023 l\u00e4uft, und die Vorfreude auf dieses gro\u00dfe Ereignis w\u00e4chst. Glasgow und Schottland mit ihrem reichen sportlichen Erbe und ihren atemberaubenden Landschaften werden sowohl den Teilnehmern als auch den Zuschauern ein unvergessliches Erlebnis bieten. Die Meisterschaften werden nicht nur die Leidenschaft f\u00fcr den Radsport zelebrieren, sondern auch die Herzlichkeit und Gastfreundschaft der schottischen Bev\u00f6lkerung demonstrieren. Diese globale Feier des Radsports wird zweifellos einen bleibenden Eindruck hinterlassen, indem sie Einzelpersonen und Gemeinschaften zum Radsport inspiriert und ein bleibendes Verm\u00e4chtnis f\u00fcr die kommenden Jahre hinterl\u00e4sst.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n","protected":false},"excerpt":{"rendered":"<p>Die mit Spannung erwarteten UCI-Radsport-Weltmeisterschaften 2023 finden vom 3. bis 13. August 2023 statt und werden die Stadt Glasgow in ihren Bann ziehen und die wundersch\u00f6ne Landschaft Schottlands durchqueren. W\u00e4hrend die weltweite Radsportgemeinde diesem prestigetr\u00e4chtigen Ereignis entgegenfiebert, laufen die Vorbereitungen f\u00fcr ein unvergessliches Erlebnis f\u00fcr Sportler und Zuschauer gleicherma\u00dfen. Glasgow, eine Stadt, die f\u00fcr ihre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2125,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-2810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>2023 UCI-Radweltmeisterschaften, 3. bis 13. August, Glasgow<\/title>\n<meta name=\"description\" content=\"2023 UCI-Radweltmeisterschaften, 3. bis 13. August, Glasgow. Klicken Sie jetzt.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2023 UCI-Radweltmeisterschaften, 3. bis 13. August, Glasgow\" \/>\n<meta property=\"og:description\" content=\"2023 UCI-Radweltmeisterschaften, 3. bis 13. August, Glasgow. Klicken Sie jetzt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wp.dev.blanca.pirstack.com\/de\/news\/2023-uci-radweltmeisterschaften-3-bis-13-august-glasgow\/\" \/>\n<meta property=\"og:site_name\" content=\"Blanca Bikes\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-18T08:58:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-16T12:50:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wp.dev.blanca.pirstack.com\/wp-content\/uploads\/2023\/11\/UCI-Logo-2023.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"piranha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"piranha\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/de\/news\/2023-uci-radweltmeisterschaften-3-bis-13-august-glasgow\/\",\"url\":\"https:\/\/wp.dev.blanca.pirstack.com\/de\/news\/2023-uci-radweltmeisterschaften-3-bis-13-august-glasgow\/\",\"name\":\"2023 UCI-Radweltmeisterschaften, 3. bis 13. August, Glasgow\",\"isPartOf\":{\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/de\/#website\"},\"datePublished\":\"2023-05-18T08:58:34+00:00\",\"dateModified\":\"2024-01-16T12:50:21+00:00\",\"author\":{\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/de\/#\/schema\/person\/1de2859f930e58ab3d39a12c1da68893\"},\"description\":\"2023 UCI-Radweltmeisterschaften, 3. bis 13. August, Glasgow. Klicken Sie jetzt.\",\"breadcrumb\":{\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/de\/news\/2023-uci-radweltmeisterschaften-3-bis-13-august-glasgow\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wp.dev.blanca.pirstack.com\/de\/news\/2023-uci-radweltmeisterschaften-3-bis-13-august-glasgow\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/de\/news\/2023-uci-radweltmeisterschaften-3-bis-13-august-glasgow\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/wp.dev.blanca.pirstack.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2023 UCI-Radweltmeisterschaften, 3. bis 13. August, Glasgow.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/de\/#website\",\"url\":\"https:\/\/wp.dev.blanca.pirstack.com\/de\/\",\"name\":\"Blanca Bikes\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wp.dev.blanca.pirstack.com\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/de\/#\/schema\/person\/1de2859f930e58ab3d39a12c1da68893\",\"name\":\"piranha\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/wp.dev.blanca.pirstack.com\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4c19455676cdb6d360be20bffa35fa495847f2ffce91fffbd483a3f13a872014?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4c19455676cdb6d360be20bffa35fa495847f2ffce91fffbd483a3f13a872014?s=96&d=mm&r=g\",\"caption\":\"piranha\"},\"sameAs\":[\"https:\/\/wp.dev.blancabikes.pirstack.com\"],\"url\":\"https:\/\/wp.dev.blanca.pirstack.com\/de\/news\/author\/piranha\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2023 UCI-Radweltmeisterschaften, 3. bis 13. August, Glasgow","description":"2023 UCI-Radweltmeisterschaften, 3. bis 13. August, Glasgow. Klicken Sie jetzt.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"2023 UCI-Radweltmeisterschaften, 3. bis 13. August, Glasgow","og_description":"2023 UCI-Radweltmeisterschaften, 3. bis 13. August, Glasgow. Klicken Sie jetzt.","og_url":"https:\/\/wp.dev.blanca.pirstack.com\/de\/news\/2023-uci-radweltmeisterschaften-3-bis-13-august-glasgow\/","og_site_name":"Blanca Bikes","article_published_time":"2023-05-18T08:58:34+00:00","article_modified_time":"2024-01-16T12:50:21+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/wp.dev.blanca.pirstack.com\/wp-content\/uploads\/2023\/11\/UCI-Logo-2023.jpg","type":"image\/jpeg"}],"author":"piranha","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"piranha","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wp.dev.blanca.pirstack.com\/de\/news\/2023-uci-radweltmeisterschaften-3-bis-13-august-glasgow\/","url":"https:\/\/wp.dev.blanca.pirstack.com\/de\/news\/2023-uci-radweltmeisterschaften-3-bis-13-august-glasgow\/","name":"2023 UCI-Radweltmeisterschaften, 3. bis 13. August, Glasgow","isPartOf":{"@id":"https:\/\/wp.dev.blanca.pirstack.com\/de\/#website"},"datePublished":"2023-05-18T08:58:34+00:00","dateModified":"2024-01-16T12:50:21+00:00","author":{"@id":"https:\/\/wp.dev.blanca.pirstack.com\/de\/#\/schema\/person\/1de2859f930e58ab3d39a12c1da68893"},"description":"2023 UCI-Radweltmeisterschaften, 3. bis 13. August, Glasgow. Klicken Sie jetzt.","breadcrumb":{"@id":"https:\/\/wp.dev.blanca.pirstack.com\/de\/news\/2023-uci-radweltmeisterschaften-3-bis-13-august-glasgow\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wp.dev.blanca.pirstack.com\/de\/news\/2023-uci-radweltmeisterschaften-3-bis-13-august-glasgow\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wp.dev.blanca.pirstack.com\/de\/news\/2023-uci-radweltmeisterschaften-3-bis-13-august-glasgow\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wp.dev.blanca.pirstack.com\/de\/"},{"@type":"ListItem","position":2,"name":"2023 UCI-Radweltmeisterschaften, 3. bis 13. August, Glasgow."}]},{"@type":"WebSite","@id":"https:\/\/wp.dev.blanca.pirstack.com\/de\/#website","url":"https:\/\/wp.dev.blanca.pirstack.com\/de\/","name":"Blanca Bikes","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wp.dev.blanca.pirstack.com\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/wp.dev.blanca.pirstack.com\/de\/#\/schema\/person\/1de2859f930e58ab3d39a12c1da68893","name":"piranha","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/wp.dev.blanca.pirstack.com\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4c19455676cdb6d360be20bffa35fa495847f2ffce91fffbd483a3f13a872014?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c19455676cdb6d360be20bffa35fa495847f2ffce91fffbd483a3f13a872014?s=96&d=mm&r=g","caption":"piranha"},"sameAs":["https:\/\/wp.dev.blancabikes.pirstack.com"],"url":"https:\/\/wp.dev.blanca.pirstack.com\/de\/news\/author\/piranha\/"}]}},"_links":{"self":[{"href":"https:\/\/wp.dev.blanca.pirstack.com\/de\/wp-json\/wp\/v2\/posts\/2810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wp.dev.blanca.pirstack.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/wp.dev.blanca.pirstack.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/wp.dev.blanca.pirstack.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/wp.dev.blanca.pirstack.com\/de\/wp-json\/wp\/v2\/comments?post=2810"}],"version-history":[{"count":1,"href":"https:\/\/wp.dev.blanca.pirstack.com\/de\/wp-json\/wp\/v2\/posts\/2810\/revisions"}],"predecessor-version":[{"id":2936,"href":"https:\/\/wp.dev.blanca.pirstack.com\/de\/wp-json\/wp\/v2\/posts\/2810\/revisions\/2936"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/wp.dev.blanca.pirstack.com\/de\/wp-json\/wp\/v2\/media\/2125"}],"wp:attachment":[{"href":"https:\/\/wp.dev.blanca.pirstack.com\/de\/wp-json\/wp\/v2\/media?parent=2810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/wp.dev.blanca.pirstack.com\/de\/wp-json\/wp\/v2\/categories?post=2810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/wp.dev.blanca.pirstack.com\/de\/wp-json\/wp\/v2\/tags?post=2810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}